{"id":15965,"date":"2017-02-15T13:58:17","date_gmt":"2017-02-15T12:58:17","guid":{"rendered":"http:\/\/www.conselharan.org\/es\/?p=15965"},"modified":"2017-02-15T13:58:17","modified_gmt":"2017-02-15T12:58:17","slug":"copos-skicenter-celebra-su-40-aniversario-con-los-refugiados","status":"publish","type":"post","link":"https:\/\/www.conselharan.org\/es\/copos-skicenter-celebra-su-40-aniversario-con-los-refugiados\/","title":{"rendered":"Copos Skicenter celebra su 40 aniversario con los refugiados"},"content":{"rendered":"<p>\u2022 <strong>Recogida de ropa para los campos de refugiados en Grecia.<\/strong><\/p>\n<p><strong>\u2022 Copos Mountain: la monta\u00f1a es lo primero.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-15959\" src=\"http:\/\/www.conselharan.org\/wp-content\/uploads\/2017\/02\/BANNER-REFUGIADOS-COPOSSKI_SEUR-1024x386.jpg\" alt=\"BANNER-REFUGIADOS-COPOSSKI_SEUR\" width=\"1024\" height=\"386\" srcset=\"https:\/\/www.conselharan.org\/wp-content\/uploads\/2017\/02\/BANNER-REFUGIADOS-COPOSSKI_SEUR-1024x386.jpg 1024w, https:\/\/www.conselharan.org\/wp-content\/uploads\/2017\/02\/BANNER-REFUGIADOS-COPOSSKI_SEUR-300x113.jpg 300w, https:\/\/www.conselharan.org\/wp-content\/uploads\/2017\/02\/BANNER-REFUGIADOS-COPOSSKI_SEUR-768x289.jpg 768w, https:\/\/www.conselharan.org\/wp-content\/uploads\/2017\/02\/BANNER-REFUGIADOS-COPOSSKI_SEUR.jpg 1656w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Cuarenta temporadas han pasado ya desde que Copos Skicenter abri\u00f3 su primera tienda dedicada al esqu\u00ed y la monta\u00f1a en su lado m\u00e1s aut\u00e9ntico. Cuarenta a\u00f1os que han transcurrido ofreciendo las mejores soluciones en pistas, tanto en prendas como en accesorios y otros materiales, convirtiendo a la marca en un referente de la Val d\u2019Aran y en el panorama estatal.<\/p>\n<p>Las personas que buscan calidad, innovaci\u00f3n y exclusividad son las que han ayudado a que Copos cumpla estos cuarenta a\u00f1os siendo l\u00edder en el sector. Por eso, <strong>Copos Skicenter<\/strong> tiene organizada una agenda apretada para ellos el resto de esta temporada. Sin embargo, tras la realidad que se vive en las fronteras de Europa, Copos Skicenter no puede apartar la vista al problema y <strong>se une a la Asociaci\u00f3n KARAAMA y la Fundaci\u00f3n SEUR como punto de recogida de ropa de abrigo durante todo el mes de febrero en su tienda de Betr\u00e9n.<\/strong><\/p>\n<p>Las im\u00e1genes que nos llegan nos dan escalofr\u00edos, debemos implicarnos para ayudar a todas esas familias, con ancianos y ni\u00f1os, muchos hu\u00e9rfanos, que se est\u00e1n congelando a las fronteras de Europa. Abrimos nuestros armarios para dar todas las viejas colecciones que ya no usamos porque tenemos m\u00e1s de lo que usamos. Estas familias, estas personas, necesitan nuestra ayuda, nuestra solidaridad, y la del resto de ciudadanos de este primer mundo. El mes de febrero es el mejor mes para hacer limpieza de armarios y cajas, el mes de febrero debemos ayudar a estas personas que viven sin nada a -18\u00ba.<\/p>\n<p>La Asociaci\u00f3n Karaama se financia a trav\u00e9s de donaciones de ropa y calzado, alimentaci\u00f3n, material escolar y donaciones econ\u00f3micas de empresas y particulares. Gracias a la colaboraci\u00f3n de la Fundaci\u00f3n Seur, responsable del transporte de estas donaciones, la ayuda humanitaria se entrega a diferentes campamentos de refugiados en Grecia, como Kasitkas, Petra o Salonica, entre otros.<\/p>\n<p>Adem\u00e1s, la Asociaci\u00f3n Karaama en colaboraci\u00f3n con <strong>Acci\u00f3n Directa Sierra Norte<\/strong> se han adentrado en un magnifico proyecto para dar de comer caliente a las personas refugiadas gracias al dise\u00f1o de la \u2018m\u00f3vil kitchen\u2019. Esta \u2018m\u00f3vil kitchen\u2019 es una cocina creada dentro de un contenedor, una aplicaci\u00f3n de dise\u00f1o social enfocada al bien com\u00fan.<\/p>\n<p>De forma paralela, durante toda esta temporada 16\/17 se van a crear otros eventos para celebrar este 40 aniversario tan especial. Ya hay fecha para las citas m\u00e1s destacadas, como:<\/p>\n<p>&#8211;<strong>GORE-TEX Hagl\u00f6fs High Camp, del 3 al 5 de marzo.<\/strong> Tras el \u00e9xito el a\u00f1o pasado, este pr\u00f3ximo 2017, Copos vuelve a colaborar junto a GORE-TEX y H\u00e4glofs en el evento GORE-TEX H\u00e4glofs High Camp. Se trata de un evento de tres d\u00edas repleto actividades en plena naturaleza donde los asistentes duermen en refugios de monta\u00f1a y son instruidos por los mejores profesionales de esqu\u00ed. El evento cuenta con la participaci\u00f3n de los deportistas de H\u00e4glofs, <strong>Joaquin Vena<\/strong> y <strong>Jonathan Larra\u00f1aga<\/strong>, adem\u00e1s de la presencia del equipo de gu\u00edas de monta\u00f1a <strong>Guide Val d\u2019Aran<\/strong>.<\/p>\n<p>&#8211;<strong>Peak Performance Girls Day, del 10 al 12 de marzo<\/strong>. Este a\u00f1o se celebra la tercera edici\u00f3n de este evento apto s\u00f3lo para chicas. Talleres y clases pr\u00e1cticas sobre esqu\u00ed de fuera de pista y de monta\u00f1a, y charlas sobre seguridad en la monta\u00f1a ser\u00e1n algunos de los protagonistas de este evento.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>40 temporadas en la Val d\u2019Aran<\/strong><\/p>\n<p>El grupo Copos es una empresa familiar y tiene su origen en 1976 de la mano de Jos\u00e9 Manuel Monge, fundador de la marca Copos. Su primera peque\u00f1a tienda dedicada a los deportes de invierno se encontraba a la salida de Vielha, vend\u00eda y alquilaba material de esqu\u00ed para los que pasaban sus vacaciones en la Val d\u2019Aran.<\/p>\n<p>Despu\u00e9s, el grupo Copos fue creciendo hasta lo que es hoy: un referente a nivel estatal de los deportes de invierno.<\/p>\n<p>Hoy el grupo Copos cuenta con varios locales especializados: <strong>Copos Moda<\/strong>, moda de esqu\u00ed con las marcas m\u00e1s punteras del sector del esqu\u00ed;<strong> Copos Skicenter<\/strong>, el mejor material duro y accesorios para los deportes de invierno, m\u00e1s un amplio nivel de esqu\u00eds de diferentes gamas y apto para cualquier persona, y un taller de reparaci\u00f3n con las m\u00e1quinas y robots m\u00e1s innovadores del sector.<\/p>\n<p>Adem\u00e1s, hace once a\u00f1os se cre\u00f3, <strong>Copos Skiclub<\/strong> y, posteriormente Copos School. El objetivo de Copos Skiclub es el fomento de la pr\u00e1ctica y la ense\u00f1anza del esqu\u00ed, tanto como afici\u00f3n como competici\u00f3n profesional.<\/p>\n<p><strong>Copos School<\/strong> fue creada hace 9 a\u00f1os y es una escuela que imparte varias modalidades de los deportes de invierno, como esqu\u00ed alpino, snowboard y esqu\u00ed n\u00f3rdico, entre otras. Aprendizaje y diversi\u00f3n van de la mano en la filosof\u00eda de esta escuela de deportes de invierno que este a\u00f1o roza su 30 aniversario de experiencia.<\/p>\n<p>Como novedad, este mismo a\u00f1o se ha presentado Copos Mountain, un nuevo concepto de espacio que fusiona moda y ropa t\u00e9cnica para ser usada cada d\u00eda. Copos Mountain cuenta en exclusiva con las marcas internacionales Luis Trenker, Dale of Norway y Hub Footwear.<\/p>\n<p>&nbsp;<\/p>\n<p>Los<strong> pilares<\/strong> del grupo Copos son: i<strong>nnovaci\u00f3n, dise\u00f1o y t\u00e9cnica.<\/strong><br \/>\n<strong> La filosof\u00eda del grupo Copos materializada<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>As\u00ed, os invitamos a formar parte de este 40 aniversario tan especial en el que todos juntos podemos ayudar a cambiar la vida y la realidad de mu\u00acchas personas o, al menos, intentar mejorar sus condiciones actuales.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>M\u00c1S INFORMACI\u00d3N<\/strong><br \/>\nCopos Skicenter Betren<br \/>\nApartamentos Elurra &#8211; 25539 Betren<br \/>\n+34 973 64 54 04<br \/>\n<a href=\"mailto:info@copos-ski.com\" target=\"_blank\">info@copos-ski.com<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Vielha, 15 de febrero de 2017<\/p>\n<p>&nbsp;<\/p>\n<p><em>Conselh Generau d&#8217;Aran: N\u00faria Sanjuan<\/em><\/p>\n<p><em>Fuente: Berta Monge S. \/ Obradora Multimedia<\/em><\/p>\n ","protected":false},"excerpt":{"rendered":"<p>\u2022 Recogida de ropa para los campos de refugiados en Grecia. \u2022 Copos Mountain: la monta\u00f1a es lo primero. &nbsp; &nbsp; Cuarenta temporadas han pasado ya desde que Copos Skicenter abri\u00f3 su primera tienda dedicada al esqu\u00ed y la monta\u00f1a en su lado m\u00e1s aut\u00e9ntico. Cuarenta a\u00f1os que han transcurrido ofreciendo las mejores soluciones en&#8230;<\/p>\n","protected":false},"author":2,"featured_media":15960,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34],"tags":[],"_links":{"self":[{"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/posts\/15965"}],"collection":[{"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/comments?post=15965"}],"version-history":[{"count":1,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/posts\/15965\/revisions"}],"predecessor-version":[{"id":15966,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/posts\/15965\/revisions\/15966"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/media\/15960"}],"wp:attachment":[{"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/media?parent=15965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/categories?post=15965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/tags?post=15965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}