{"id":22258,"date":"2018-05-14T12:39:52","date_gmt":"2018-05-14T10:39:52","guid":{"rendered":"http:\/\/www.conselharan.org\/?p=22258"},"modified":"2018-05-14T12:39:52","modified_gmt":"2018-05-14T10:39:52","slug":"la-red-de-museos-de-las-tierras-de-lleida-y-aran-inicia-la-celebracion-del-dia-internacional-de-los-museos-en-vilac","status":"publish","type":"post","link":"https:\/\/www.conselharan.org\/es\/la-red-de-museos-de-las-tierras-de-lleida-y-aran-inicia-la-celebracion-del-dia-internacional-de-los-museos-en-vilac\/","title":{"rendered":"La Red de Museos de las Tierras de Lleida y Aran inicia la celebraci\u00f3n del D\u00eda Internacional de los Museos en Vilac"},"content":{"rendered":"<p>Vielha, 14 de mayo de 2018.- Del 14 al 20 de mayo con el lema <strong>\u00abMuseos hiperconectados: nuevos enfoques, nuevos p\u00fablicos\u00bb<\/strong>, la Red de museos de las Tierras de Lleida y Aran celebra las actividades del D\u00eda Internacional de los Museos (DIM), que se celebra anualmente el 18 de mayo, con el planteamiento de un enigma virtual que, siguiendo el <strong>hashtag #DIMisteri2018<\/strong>, se dirigir\u00e1 a los usuarios de las redes sociales. En este juego l\u00fadico cada museo publicar\u00e1 unas im\u00e1genes en las redes \u00abinformando\u00bb sobre un hecho misterioso relacionado con las respectivas colecciones. A partir de ah\u00ed, los usuarios tendr\u00e1n que averiguar qu\u00e9 est\u00e1 pasando en cada museo y qu\u00e9 conexi\u00f3n se ha establecido entre los museos de la red.<\/p>\n<p><a href=\"http:\/\/www.conselharan.org\/wp-content\/uploads\/2018\/05\/Lesgl\u00e9sia-de-Vilac-acull-la-presentaci\u00f3-del-DIM.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-22255\" src=\"http:\/\/www.conselharan.org\/wp-content\/uploads\/2018\/05\/Lesgl\u00e9sia-de-Vilac-acull-la-presentaci\u00f3-del-DIM-1024x683.jpeg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/www.conselharan.org\/wp-content\/uploads\/2018\/05\/Lesgl\u00e9sia-de-Vilac-acull-la-presentaci\u00f3-del-DIM-1024x683.jpeg 1024w, https:\/\/www.conselharan.org\/wp-content\/uploads\/2018\/05\/Lesgl\u00e9sia-de-Vilac-acull-la-presentaci\u00f3-del-DIM-300x200.jpeg 300w, https:\/\/www.conselharan.org\/wp-content\/uploads\/2018\/05\/Lesgl\u00e9sia-de-Vilac-acull-la-presentaci\u00f3-del-DIM-768x512.jpeg 768w, https:\/\/www.conselharan.org\/wp-content\/uploads\/2018\/05\/Lesgl\u00e9sia-de-Vilac-acull-la-presentaci\u00f3-del-DIM.jpeg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>El planteamiento del DIM de este a\u00f1o responde a que las nuevas tecnolog\u00edas permiten a los museos llegar m\u00e1s all\u00e1 de su p\u00fablico habitual, presentando sus colecciones de una forma diferente y totalmente innovadora. Para promover las conexiones entre museos y las nuevas formas de comunicaci\u00f3n con los usuarios, los museos de la red promover\u00e1n un juego virtual.<br \/>\n<iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fmuseusval.daran%2Fposts%2F1814578468606819&amp;width=500\" width=\"500\" height=\"752\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p>El martes, d\u00eda <strong>15 de mayo a las 12:00h tendr\u00e1 lugar en la iglesia de Vilac<\/strong> una rueda de prensa para presentar las actividades que se llevar\u00e1n a cabo en la Red de Museos de las Tierras de Lleida y Aran para celebrar el d\u00eda Internacional de los Museos y la Noche de los Museos, en la que participar\u00e1n <strong>Carmen Berg\u00e9s<\/strong>, presidenta de la Red de Museos de las Tierras de Lleida y Aran, y <strong>Carla del Valle<\/strong>, directora del Museo de la Val d&#8217;Aran.<\/p>\n<p>El DIM es un evento organizado por el Comit\u00e9 Internacional de los Museos (ICOM) desde el a\u00f1o 1977, que tiene como objetivo concienciar a los ciudadanos sobre el papel de los museos en el desarrollo de las sociedades.<\/p>\n<p>Forman parte de la Red de Museos de las Tierras de Lleida y Aran, el Ecomuseo de las Valls d&#8217;\u00c0neu (Esterri d&#8217;\u00c0neu), el Museo Comarcal de Cervera (Cervera), el Museo Comarcal del Urgell (T\u00e0rrega), el Museo de Isona y la Conca Dell\u00e0 (Isona y Conca Dell\u00e0), el Museo de Arte Jaume Morera (Lleida), el Museo de la Noguera (Balaguer), el Museo de Lleida: Diocesano y Comarcal (Lleida), el Museo de la Val d\u2019Aran (Vielha e Mijaran), el Museo Diocesano de Urgell (La Seu d\u2019Urgell), el Museo Diocesano y Comarcal de Solsona (Solsona) y el Museo de Guissona (Guissona).<\/p>\n ","protected":false},"excerpt":{"rendered":"<p>Vielha, 14 de mayo de 2018.- Del 14 al 20 de mayo con el lema \u00abMuseos hiperconectados: nuevos enfoques, nuevos p\u00fablicos\u00bb, la Red de museos de las Tierras de Lleida y Aran celebra las actividades del D\u00eda Internacional de los Museos (DIM), que se celebra anualmente el 18 de mayo, con el planteamiento de un&#8230;<\/p>\n","protected":false},"author":2,"featured_media":22255,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34],"tags":[],"_links":{"self":[{"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/posts\/22258"}],"collection":[{"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/comments?post=22258"}],"version-history":[{"count":1,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/posts\/22258\/revisions"}],"predecessor-version":[{"id":22259,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/posts\/22258\/revisions\/22259"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/media\/22255"}],"wp:attachment":[{"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/media?parent=22258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/categories?post=22258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/tags?post=22258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}