{"id":43484,"date":"2021-07-08T14:26:03","date_gmt":"2021-07-08T12:26:03","guid":{"rendered":"https:\/\/www.conselharan.org\/es-agents-de-miei-ambient-deth-conselh-generau-realizaran-quauqui-servicis-damb-bicicletes-electriques\/"},"modified":"2021-07-08T14:27:11","modified_gmt":"2021-07-08T12:27:11","slug":"es-agents-de-miei-ambient-deth-conselh-generau-realizaran-quauqui-servicis-damb-bicicletes-electriques","status":"publish","type":"post","link":"https:\/\/www.conselharan.org\/es\/es-agents-de-miei-ambient-deth-conselh-generau-realizaran-quauqui-servicis-damb-bicicletes-electriques\/","title":{"rendered":"Los Agentes de Medio Ambiente del Conselh Generau realizar\u00e1n algunos servicios con bicicletas el\u00e9ctricas"},"content":{"rendered":"<p><a href=\"https:\/\/www.conselharan.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-08-at-14.18.35.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-43476 size-full\" src=\"https:\/\/www.conselharan.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-08-at-14.18.35.jpeg\" alt=\"\" width=\"1024\" height=\"768\" srcset=\"https:\/\/www.conselharan.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-08-at-14.18.35.jpeg 1024w, https:\/\/www.conselharan.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-08-at-14.18.35-300x225.jpeg 300w, https:\/\/www.conselharan.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-08-at-14.18.35-768x576.jpeg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<ul>\n<li>\n<h3><strong>The Secret Spot de Vielha ceder\u00e1 dos e-bikes a los Agentes de Medio Ambiente del Conselh Generau d\u2019Aran durante varios d\u00edas en los meses de julio y agosto para que puedan realizar distintos servicios en las \u00e1reas con m\u00e1s afluencia de tr\u00e1nsito durante el verano<\/strong><\/h3>\n<\/li>\n<\/ul>\n<p>Los Agentes de Medio Ambiente del Conselh Generau d\u2019Aran realizar\u00e1n, durante diferentes d\u00edas de los meses de julio y agosto, algunos servicios con bicicletas el\u00e9ctricas o e-bikes.<\/p>\n<p>\u201cQueremos agradecer a la tienda The Secret Spot de Vielha que haya tenido esta iniciativa y que nos ceda dos bicicletas para nuestros Agentes de Medio Ambiente\u201d, aseguraba el consejero de Territorio, Paisaje y Gesti\u00f3n Ambiental, Franc\u00e9s Bruna, a\u00f1adiendo que: \u201caprovecharemos este medio de transporte para los servicios en las \u00e1reas m\u00e1s transitadas durante julio y agosto como la Bassa d\u2019Oles, la Artiga de Lin o Tuca, facilitando as\u00ed el acceso de los Agentes y disminuyendo el n\u00famero de veh\u00edculos en estas zonas\u201d.<\/p>\n<p>Durante estos servicios se realizar\u00e1n controles de fauna y pesca, controles de acceso motorizado, de acampadas, de barbacoas o pruebas deportivas, entre otros.<\/p>\n<p><a href=\"https:\/\/www.conselharan.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-07-at-20.52.19.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-43479 size-full\" src=\"https:\/\/www.conselharan.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-07-at-20.52.19.jpeg\" alt=\"\" width=\"884\" height=\"1024\" srcset=\"https:\/\/www.conselharan.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-07-at-20.52.19.jpeg 884w, https:\/\/www.conselharan.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-07-at-20.52.19-259x300.jpeg 259w, https:\/\/www.conselharan.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-07-at-20.52.19-768x890.jpeg 768w\" sizes=\"(max-width: 884px) 100vw, 884px\" \/><\/a><\/p>\n ","protected":false},"excerpt":{"rendered":"<p>The Secret Spot de Vielha ceder\u00e1 dos e-bikes a los Agentes de Medio Ambiente del Conselh Generau d\u2019Aran durante varios d\u00edas en los meses de julio y agosto para que puedan realizar distintos servicios en las \u00e1reas con m\u00e1s afluencia de tr\u00e1nsito durante el verano Los Agentes de Medio Ambiente del Conselh Generau d\u2019Aran realizar\u00e1n,&#8230;<\/p>\n","protected":false},"author":10,"featured_media":43478,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[126,34],"tags":[],"_links":{"self":[{"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/posts\/43484"}],"collection":[{"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/comments?post=43484"}],"version-history":[{"count":1,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/posts\/43484\/revisions"}],"predecessor-version":[{"id":43485,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/posts\/43484\/revisions\/43485"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/media\/43478"}],"wp:attachment":[{"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/media?parent=43484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/categories?post=43484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/tags?post=43484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}