{"id":43801,"date":"2021-07-24T15:18:30","date_gmt":"2021-07-24T13:18:30","guid":{"rendered":"https:\/\/www.conselharan.org\/se-senhalizen-es-establiments-collaboradors-deth-camin-de-santiago-aran-pirineus\/"},"modified":"2021-07-24T15:20:06","modified_gmt":"2021-07-24T13:20:06","slug":"se-senhalizen-es-establiments-collaboradors-deth-camin-de-santiago-aran-pirineus","status":"publish","type":"post","link":"https:\/\/www.conselharan.org\/es\/se-senhalizen-es-establiments-collaboradors-deth-camin-de-santiago-aran-pirineus\/","title":{"rendered":"Se se\u00f1alizan los establecimientos colaboradores del Camino de Santiago Aran Pirineos"},"content":{"rendered":"<p><a href=\"https:\/\/www.conselharan.org\/wp-content\/uploads\/2021\/07\/Camino-de-Santiago-Aran-Pirineos.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-43796 size-large\" src=\"https:\/\/www.conselharan.org\/wp-content\/uploads\/2021\/07\/Camino-de-Santiago-Aran-Pirineos-1024x575.png\" alt=\"\" width=\"1024\" height=\"575\" srcset=\"https:\/\/www.conselharan.org\/wp-content\/uploads\/2021\/07\/Camino-de-Santiago-Aran-Pirineos-1024x575.png 1024w, https:\/\/www.conselharan.org\/wp-content\/uploads\/2021\/07\/Camino-de-Santiago-Aran-Pirineos-300x169.png 300w, https:\/\/www.conselharan.org\/wp-content\/uploads\/2021\/07\/Camino-de-Santiago-Aran-Pirineos-768x431.png 768w, https:\/\/www.conselharan.org\/wp-content\/uploads\/2021\/07\/Camino-de-Santiago-Aran-Pirineos-1536x863.png 1536w, https:\/\/www.conselharan.org\/wp-content\/uploads\/2021\/07\/Camino-de-Santiago-Aran-Pirineos-2048x1150.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<ul>\n<li>\n<h3><strong>Alrededor de una quincena de establecimientos hoteleros y de restauraci\u00f3n araneses colaboran con el Camino de Santiago Aran Pirineos, que llevar\u00e1 a los peregrinos de Sant Bertrand de Comminges, travesando la Val d\u2019Aran, Alta Ribagor\u00e7a y Huesca hasta conectar con el Camino de Santiago catal\u00e1n, una iniciativa promovida por el Conselh Generau d\u2019Aran, la Communaut\u00e9 de Communes Pyr\u00e9n\u00e9es Haut Garonnaises, el Consell Comarcal de l\u2019Alta Ribagor\u00e7a y la Diputaci\u00f3n Provincial de Huesca<\/strong><\/h3>\n<\/li>\n<\/ul>\n<p>El Conselh Generau d\u2019Aran, a trav\u00e9s de Foment Torisme Val d\u2019Aran, otorgar\u00e1 en los pr\u00f3ximos d\u00edas a los establecimientos adheridos a la iniciativa del Camino de Santiago Aran Pirineos las placas que les identifican como Establecimientos Amigos del Camino de Santiago.<\/p>\n<p>\u201cLa idea de recuperar este camino olvidado por los pelegrinos, pero que ha mantenido la conexi\u00f3n entre los territorios vecinos, se presenta como una nueva oportunidad de desarrollo tur\u00edstico fuera de la temporada de invierno para nuestro territorio\u201d, afirma el vices\u00edndico y consejero de Econom\u00eda, Turismo y Promoci\u00f3n Econ\u00f3mica, Juan Antonio Serrano, a\u00f1adiendo que: \u201cel Camino de Santiago cuenta con un gran reconocimiento y prestigio a nivel mundial y el hecho de tener una ruta de este camino que atraviesa nuestro territorio nos sit\u00faa en el mapa de muchos peregrinos y supone un importante impulso tur\u00edstico que nos puede ayudar tambi\u00e9n a diversificar nuestra econom\u00eda\u201d.<\/p>\n<p>Por su parte, el tambi\u00e9n consejero de Econom\u00eda, Turismo y Promoci\u00f3n Econ\u00f3mica, Josep Canut, manifestaba que: \u201cdesde el gobierno del Conselh Generau d\u2019Aran queremos agradecer el trabajo de la Asociaci\u00f3n Amigos del Camino de Santiago de la Val d\u2019Aran y, m\u00e1s concretamente, a Ignacio Aldea, y los difuntos Jos\u00e9 Antonio Mart\u00ednez \u00cd\u00f1igo y su mujer Maribel, que fueron los propulsores iniciales de este proyecto, as\u00ed como la Asociaci\u00f3n Volentaris Val d\u2019Aran por el trabajo que han realizado para hacer realidad este Camino\u201d.<\/p>\n<p>El Camino de Santiago Aran Pirineos, que va desde Saint Bertrand de Comminges a Berbegal recorriendo la Val d\u2019Aran por Les, Boss\u00f2st, Es B\u00f2rdes y Vielha, consta de 14 etapas que suman 246,50 km de recorrido cargados de historia.<\/p>\n<p>El itinerario est\u00e1 totalmente se\u00f1alizado con las marcas de los senderos de Gran Recorrido (GR-211 y sus variantes en el Valle de Aran, y GR-17 en los tramos de la Alta Ribagor\u00e7a catalana y Huesca).<\/p>\n ","protected":false},"excerpt":{"rendered":"<p>Alrededor de una quincena de establecimientos hoteleros y de restauraci\u00f3n araneses colaboran con el Camino de Santiago Aran Pirineos, que llevar\u00e1 a los peregrinos de Sant Bertrand de Comminges, travesando la Val d\u2019Aran, Alta Ribagor\u00e7a y Huesca hasta conectar con el Camino de Santiago catal\u00e1n, una iniciativa promovida por el Conselh Generau d\u2019Aran, la Communaut\u00e9&#8230;<\/p>\n","protected":false},"author":10,"featured_media":43798,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34,137],"tags":[],"_links":{"self":[{"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/posts\/43801"}],"collection":[{"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/comments?post=43801"}],"version-history":[{"count":1,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/posts\/43801\/revisions"}],"predecessor-version":[{"id":43802,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/posts\/43801\/revisions\/43802"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/media\/43798"}],"wp:attachment":[{"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/media?parent=43801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/categories?post=43801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/tags?post=43801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}