{"id":59742,"date":"2024-11-07T13:55:02","date_gmt":"2024-11-07T12:55:02","guid":{"rendered":"https:\/\/www.conselharan.org\/?p=59742"},"modified":"2024-11-07T13:58:08","modified_gmt":"2024-11-07T12:58:08","slug":"eth-centre-de-lauegi-deth-conselh-generau-daran-participe-ena-xviii-trobada-de-centres-de-prediccion-de-lauegi-des-pireneus","status":"publish","type":"post","link":"https:\/\/www.conselharan.org\/es\/eth-centre-de-lauegi-deth-conselh-generau-daran-participe-ena-xviii-trobada-de-centres-de-prediccion-de-lauegi-des-pireneus\/","title":{"rendered":"Eth Centre de Lauegi deth Conselh Generau d\u2019Aran participe ena XVIII trobada de Centres de Prediccion de Lauegi des Piren\u00e8us"},"content":{"rendered":"<p><a href=\"https:\/\/www.conselharan.org\/es\/eth-centre-de-lauegi-deth-conselh-generau-daran-participe-ena-xviii-trobada-de-centres-de-prediccion-de-lauegi-des-pireneus\/centre-lauegi-1-2\/\" rel=\"attachment wp-att-59743\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-59743\" src=\"https:\/\/www.conselharan.org\/wp-content\/uploads\/2024\/11\/Centre-Lauegi-1-1024x768.jpeg\" alt=\"\" width=\"1024\" height=\"768\" srcset=\"https:\/\/www.conselharan.org\/wp-content\/uploads\/2024\/11\/Centre-Lauegi-1-1024x768.jpeg 1024w, https:\/\/www.conselharan.org\/wp-content\/uploads\/2024\/11\/Centre-Lauegi-1-300x225.jpeg 300w, https:\/\/www.conselharan.org\/wp-content\/uploads\/2024\/11\/Centre-Lauegi-1-768x576.jpeg 768w, https:\/\/www.conselharan.org\/wp-content\/uploads\/2024\/11\/Centre-Lauegi-1-1536x1152.jpeg 1536w, https:\/\/www.conselharan.org\/wp-content\/uploads\/2024\/11\/Centre-Lauegi-1.jpeg 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<ul>\n<li><strong>Es tecnics deth Centre de Lauegi deth Conselh Generau d\u2019Aran an participat ena XVIII trobada de Centres de Prediccion de Lauegi des Piren\u00e8us, que s\u2019a h\u00e8t en Saragossa, eth 28 e 29 d\u2019octobre<\/strong><\/li>\n<\/ul>\n<p>Aguesta trobada se h\u00e8 cada dus ans, ena tardor, e s\u2019organize en torns per part d\u2019un des centres publics regionaus que h\u00e8n prediccion de lauegi. Enguan s\u2019a h\u00e8t ena seden\u00e7a dera Ag\u00e9ncia Estatau de Meteorologia (AEMET) en Saragossa, a on era institucion h\u00e8 era prediccion meteorologica e nivologica entara montanha.<\/p>\n<p>Tanben i an participat er Institut Cartografic e Geologic de Catalonha (ICGC), eth Servici de Meteorologia Nacionau d\u2019And\u00f2rra (SMA) e MeteoFrance.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.conselharan.org\/es\/eth-centre-de-lauegi-deth-conselh-generau-daran-participe-ena-xviii-trobada-de-centres-de-prediccion-de-lauegi-des-pireneus\/centre-de-lauegi-2-2\/\" rel=\"attachment wp-att-59736\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-59736\" src=\"https:\/\/www.conselharan.org\/wp-content\/uploads\/2024\/10\/Centre-de-Lauegi-2-1024x768.jpg\" alt=\"\" width=\"1024\" height=\"768\" srcset=\"https:\/\/www.conselharan.org\/wp-content\/uploads\/2024\/10\/Centre-de-Lauegi-2-1024x768.jpg 1024w, https:\/\/www.conselharan.org\/wp-content\/uploads\/2024\/10\/Centre-de-Lauegi-2-300x225.jpg 300w, https:\/\/www.conselharan.org\/wp-content\/uploads\/2024\/10\/Centre-de-Lauegi-2-768x576.jpg 768w, https:\/\/www.conselharan.org\/wp-content\/uploads\/2024\/10\/Centre-de-Lauegi-2-1536x1152.jpg 1536w, https:\/\/www.conselharan.org\/wp-content\/uploads\/2024\/10\/Centre-de-Lauegi-2.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Pendent es dues jornades, es centres an h\u00e8t presentacions sus proj\u00e8ctes d\u2019observacion deth celh de nh\u00e8u e de prediccion deth perilh de lauegi damb es dades d\u2019estacions meteorologiques, tecniques de teledeteccion e mod\u00e8ls d\u2019intellig\u00e9ncia artificiau. Tanben a servit ent\u00e0 escambiar experi\u00e9ncies, informacions e actualizacions relacionades damb era prediccion de lauegi operativa laguens deth cont\u00e8xte europ\u00e8u des EAWS (European Avalanche Warning Services) e tanben t\u00e0 refortir es canaus de comunicacion comuns ent\u00e0 trabalhar de man\u00e8ra collaborativa ena prediccion de lauegi.<\/p>\n<p>&nbsp;<\/p>\n<p><em>Vielha,\u00a0 7 de noveme 2024<\/em><\/p>\n ","protected":false},"excerpt":{"rendered":"<p>Es tecnics deth Centre de Lauegi deth Conselh Generau d\u2019Aran an participat ena XVIII trobada de Centres de Prediccion de Lauegi des Piren\u00e8us, que s\u2019a h\u00e8t en Saragossa, eth 28 e 29 d\u2019octobre Aguesta trobada se h\u00e8 cada dus ans, ena tardor, e s\u2019organize en torns per part d\u2019un des centres publics regionaus que h\u00e8n&#8230;<\/p>\n","protected":false},"author":2,"featured_media":59745,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,34,37],"tags":[],"_links":{"self":[{"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/posts\/59742"}],"collection":[{"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/comments?post=59742"}],"version-history":[{"count":2,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/posts\/59742\/revisions"}],"predecessor-version":[{"id":59795,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/posts\/59742\/revisions\/59795"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/media\/59745"}],"wp:attachment":[{"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/media?parent=59742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/categories?post=59742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/tags?post=59742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}