{"id":63669,"date":"2025-08-06T13:20:02","date_gmt":"2025-08-06T11:20:02","guid":{"rendered":"https:\/\/www.conselharan.org\/?p=63669"},"modified":"2025-08-06T14:15:01","modified_gmt":"2025-08-06T12:15:01","slug":"nuevo-ciclo-de-conciertos-de-verano-en-las-iglesias-de-la-val-daran","status":"publish","type":"post","link":"https:\/\/www.conselharan.org\/es\/nuevo-ciclo-de-conciertos-de-verano-en-las-iglesias-de-la-val-daran\/","title":{"rendered":"Nuevo Ciclo de Conciertos de Verano en las iglesias de la Val d\u2019Aran"},"content":{"rendered":"<p><a href=\"https:\/\/www.conselharan.org\/es\/nuevo-ciclo-de-conciertos-de-verano-en-las-iglesias-de-la-val-daran\/imagen-de-whatsapp-2025-08-04-a-las-16-28-26_0ba02864-2\/\" rel=\"attachment wp-att-63657\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-63657\" src=\"https:\/\/www.conselharan.org\/wp-content\/uploads\/2025\/08\/Imagen-de-WhatsApp-2025-08-04-a-las-16.28.26_0ba02864-1024x1024.jpg\" alt=\"\" width=\"1024\" height=\"1024\" srcset=\"https:\/\/www.conselharan.org\/wp-content\/uploads\/2025\/08\/Imagen-de-WhatsApp-2025-08-04-a-las-16.28.26_0ba02864-1024x1024.jpg 1024w, https:\/\/www.conselharan.org\/wp-content\/uploads\/2025\/08\/Imagen-de-WhatsApp-2025-08-04-a-las-16.28.26_0ba02864-300x300.jpg 300w, https:\/\/www.conselharan.org\/wp-content\/uploads\/2025\/08\/Imagen-de-WhatsApp-2025-08-04-a-las-16.28.26_0ba02864-150x150.jpg 150w, https:\/\/www.conselharan.org\/wp-content\/uploads\/2025\/08\/Imagen-de-WhatsApp-2025-08-04-a-las-16.28.26_0ba02864-768x768.jpg 768w, https:\/\/www.conselharan.org\/wp-content\/uploads\/2025\/08\/Imagen-de-WhatsApp-2025-08-04-a-las-16.28.26_0ba02864-270x270.jpg 270w, https:\/\/www.conselharan.org\/wp-content\/uploads\/2025\/08\/Imagen-de-WhatsApp-2025-08-04-a-las-16.28.26_0ba02864-207x207.jpg 207w, https:\/\/www.conselharan.org\/wp-content\/uploads\/2025\/08\/Imagen-de-WhatsApp-2025-08-04-a-las-16.28.26_0ba02864-75x75.jpg 75w, https:\/\/www.conselharan.org\/wp-content\/uploads\/2025\/08\/Imagen-de-WhatsApp-2025-08-04-a-las-16.28.26_0ba02864.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<ul>\n<li>\n<h3><strong>El encuentro musical incluye cuatro conciertos en las iglesias de Nuestra Se\u00f1ora del Rosario de Es B\u00f2rdes, San F\u00e9lix de Vilac, la capilla de San Blas de Les y la iglesia de San Juli\u00e1n de Gar\u00f2s.<\/strong><\/h3>\n<\/li>\n<\/ul>\n<p>En la agenda cultural de este verano no pueden faltar las actividades musicales que acoge nuestro patrimonio, y que este a\u00f1o contar\u00e1 con un nuevo ciclo de conciertos. El Departamento de Torisme, Promocion Economica e Com\u00e8r\u00e7 del Conselh Generau d\u2019Aran ha creado un programa de cuatro conciertos, que tendr\u00e1n lugar los viernes de este mes de agosto, con composiciones de diversos estilos musicales.<\/p>\n<p>El primer concierto ser\u00e1 el viernes 8 de agosto en la iglesia de Nuestra Se\u00f1ora del Rosario de Es B\u00f2rdes, con el Cuarteto Teixidor de cuerda, a las 20:00 horas.<\/p>\n<p>El Cuarteto de cuerda y flauta Prysma ofrecer\u00e1 un amplio repertorio en la iglesia de San F\u00e9lix de Vilac el viernes 15 de agosto, a las 19:30 horas.<\/p>\n<p>Una tercera actuaci\u00f3n musical reunir\u00e1 al cuarteto espiritual negro Black Birds en la capilla de San Blas de Les, el viernes 22 de agosto, a las 19:30 horas.<\/p>\n<p>Este ciclo de conciertos de verano se cerrar\u00e1 el viernes 29 de agosto con el tr\u00edo de cuerda y piano Pop Piano Quartet, en la iglesia de San Juli\u00e1n de Gar\u00f2s.<\/p>\n<p>Todos los conciertos de este Ciclo de Verano son gratuitos y abiertos a todos los p\u00fablicos.<\/p>\n<p><em>Vielha, 6 de agosto de 2025<\/em><\/p>\n ","protected":false},"excerpt":{"rendered":"<p>El encuentro musical incluye cuatro conciertos en las iglesias de Nuestra Se\u00f1ora del Rosario de Es B\u00f2rdes, San F\u00e9lix de Vilac, la capilla de San Blas de Les y la iglesia de San Juli\u00e1n de Gar\u00f2s. En la agenda cultural de este verano no pueden faltar las actividades musicales que acoge nuestro patrimonio, y que&#8230;<\/p>\n","protected":false},"author":2,"featured_media":63657,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,795,52,34,37,137],"tags":[],"_links":{"self":[{"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/posts\/63669"}],"collection":[{"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/comments?post=63669"}],"version-history":[{"count":2,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/posts\/63669\/revisions"}],"predecessor-version":[{"id":63674,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/posts\/63669\/revisions\/63674"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/media\/63657"}],"wp:attachment":[{"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/media?parent=63669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/categories?post=63669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.conselharan.org\/es\/wp-json\/wp\/v2\/tags?post=63669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}